{"id":81601,"date":"2023-11-10T12:20:36","date_gmt":"2023-11-10T11:20:36","guid":{"rendered":"https:\/\/subblim.com\/funda-tablet-universal-freecam-case-9-6%e2%80%b3-11%e2%80%b3-rojo\/"},"modified":"2026-06-01T00:10:43","modified_gmt":"2026-05-31T22:10:43","slug":"etui-universel-pour-tablette-freecam-case-9-6%e2%80%b3-11%e2%80%b3-rouge","status":"publish","type":"product","link":"https:\/\/subblim.com\/fr\/etui-universel-pour-tablette-freecam-case-9-6%e2%80%b3-11%e2%80%b3-rouge\/","title":{"rendered":"\u00c9tui universel pour tablette Freecam Case 9,6&Prime; 11&Prime; Rouge"},"content":{"rendered":"<p>L&rsquo;\u00e9tui universel pour tablette Freecam est id\u00e9al pour prot\u00e9ger votre appareil et, gr\u00e2ce \u00e0 un syst\u00e8me de rabat magn\u00e9tique con\u00e7u par SUBBLIM, qui laisse l&rsquo;arri\u00e8re libre, vous pouvez prendre des photos ou des vid\u00e9os. <br \/>La finition ext\u00e9rieure avec une finition toucher tissu et les coutures exquises conf\u00e8rent au produit un aspect de haute qualit\u00e9.<\/p>\n<p>Le format support et support de type SmartCover est antid\u00e9rapant et permet de placer la tablette dans diff\u00e9rents angles de visualisation et d&rsquo;\u00e9criture. <br \/>Les ports de connexion et les boutons restent accessibles m\u00eame lorsque votre tablette est dans l&rsquo;\u00e9tui, avec de grandes ouvertures sur tous les c\u00f4t\u00e9s pour un acc\u00e8s facile.<\/p>\n<ul>\n<li>Con\u00e7u pour les tablettes jusqu&rsquo;\u00e0 11 pouces<\/li>\n<li>\n<p>Finition toucher tissu<\/p>\n<\/li>\n<li>\n<p>Acc\u00e8s complet \u00e0 tous les boutons et connecteurs<\/p>\n<\/li>\n<li>\n<p>Position support type SmartCover<\/p>\n<\/li>\n<li>\n<p>Adaptable \u00e0 tous les mod\u00e8les de tablettes gr\u00e2ce \u00e0 un syst\u00e8me de fixation exclusif en silicone qui n&rsquo;ab\u00eeme pas votre tablette<\/p>\n<\/li>\n<li>\n<p>Int\u00e9rieur doux et velout\u00e9<\/p>\n<\/li>\n<li>\n<p>Rabat arri\u00e8re rabattable qui vous permet d&rsquo;utiliser l&rsquo;appareil photo sans retirer la tablette de l&rsquo;\u00e9tui<\/p>\n<\/li>\n<li>\n<p>Fermeture s\u00e9curis\u00e9e avec bande \u00e9lastique<\/p>\n<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>EAN\u00a0: \u00c9tui pour tablette Freecam noir (SUB-CUT-2FC001) 8436586740832\u00a0; \u00c9tui pour tablette Freecam rouge (SUB-CUT-2FC002) 8436586740849\u00a0; \u00c9tui pour tablette Freecam violet (SUB-CUT-2FC003) 8436586740856<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;\u00e9tui universel pour tablette Freecam est id\u00e9al pour prot\u00e9ger votre appareil. Son syst\u00e8me de rabat magn\u00e9tique, con\u00e7u par SUBBLIM, lib\u00e8re l&rsquo;arri\u00e8re de votre appareil et vous permet de prendre des photos ou des vid\u00e9os.<\/p>\n","protected":false},"featured_media":77885,"template":"","meta":[],"product_brand":[],"product_cat":[2311],"product_tag":[],"class_list":{"0":"post-81601","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-couleurs-unies-fr","8":"first","9":"outofstock","10":"sale","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product\/81601","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product\/81601\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/media\/77885"}],"wp:attachment":[{"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/media?parent=81601"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product_brand?post=81601"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product_cat?post=81601"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/subblim.com\/fr\/wp-json\/wp\/v2\/product_tag?post=81601"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}